{"id":6590,"count":1,"description":"","link":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/","name":"Isabelle Renard","slug":"isabelle-renard","taxonomy":"author","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Isabelle Renard - Evidency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evidency.io\/es\/author\/isabelle-renard\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Isabelle Renard - Evidency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evidency.io\/es\/author\/isabelle-renard\/\" \/>\n<meta property=\"og:site_name\" content=\"Evidency\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evidency.io\/wp-content\/uploads\/2025\/11\/Preview-website-pages.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/evidency.io\/es\/author\/isabelle-renard\/\",\"url\":\"https:\/\/evidency.io\/es\/author\/isabelle-renard\/\",\"name\":\"Archives des Isabelle Renard - Evidency\",\"isPartOf\":{\"@id\":\"https:\/\/evidency.io\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/evidency.io\/es\/author\/isabelle-renard\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/evidency.io\/es\/author\/isabelle-renard\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Evidency\",\"item\":\"https:\/\/evidency.io\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isabelle Renard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/evidency.io\/es\/#website\",\"url\":\"https:\/\/evidency.io\/es\/\",\"name\":\"Evidency\",\"description\":\"Sp\u00e9cialiste de la preuve num\u00e9rique\",\"publisher\":{\"@id\":\"https:\/\/evidency.io\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/evidency.io\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/evidency.io\/es\/#organization\",\"name\":\"Evidency\",\"url\":\"https:\/\/evidency.io\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/evidency.io\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/evidency.io\/wp-content\/uploads\/2024\/09\/header-logo.svg\",\"contentUrl\":\"https:\/\/evidency.io\/wp-content\/uploads\/2024\/09\/header-logo.svg\",\"width\":275,\"height\":58,\"caption\":\"Evidency\"},\"image\":{\"@id\":\"https:\/\/evidency.io\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/evidency-io\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Isabelle Renard - Evidency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des Isabelle Renard - Evidency","og_url":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/","og_site_name":"Evidency","og_image":[{"width":1200,"height":675,"url":"https:\/\/evidency.io\/wp-content\/uploads\/2025\/11\/Preview-website-pages.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/","url":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/","name":"Archives des Isabelle Renard - Evidency","isPartOf":{"@id":"https:\/\/evidency.io\/es\/#website"},"breadcrumb":{"@id":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/evidency.io\/es\/author\/isabelle-renard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Evidency","item":"https:\/\/evidency.io\/es\/"},{"@type":"ListItem","position":2,"name":"Isabelle Renard"}]},{"@type":"WebSite","@id":"https:\/\/evidency.io\/es\/#website","url":"https:\/\/evidency.io\/es\/","name":"Evidency","description":"Sp\u00e9cialiste de la preuve num\u00e9rique","publisher":{"@id":"https:\/\/evidency.io\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evidency.io\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/evidency.io\/es\/#organization","name":"Evidency","url":"https:\/\/evidency.io\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evidency.io\/es\/#\/schema\/logo\/image\/","url":"https:\/\/evidency.io\/wp-content\/uploads\/2024\/09\/header-logo.svg","contentUrl":"https:\/\/evidency.io\/wp-content\/uploads\/2024\/09\/header-logo.svg","width":275,"height":58,"caption":"Evidency"},"image":{"@id":"https:\/\/evidency.io\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/evidency-io\/"]}]}},"_links":{"self":[{"href":"https:\/\/evidency.io\/es\/wp-json\/wp\/v2\/ppma_author\/6590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evidency.io\/es\/wp-json\/wp\/v2\/ppma_author"}],"about":[{"href":"https:\/\/evidency.io\/es\/wp-json\/wp\/v2\/taxonomies\/author"}],"wp:post_type":[{"href":"https:\/\/evidency.io\/es\/wp-json\/wp\/v2\/posts?ppma_author=6590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}